{"id":18215,"date":"2013-09-17T09:05:34","date_gmt":"2013-09-17T13:05:34","guid":{"rendered":"http:\/\/staging.hispanicizewire.com\/?p=2176"},"modified":"2017-03-10T10:25:19","modified_gmt":"2017-03-10T15:25:19","slug":"latism13-recognizes-top-latina-influencer-laura-termini","status":"publish","type":"post","link":"https:\/\/www.noticiasnewswire.com\/es\/latism13-recognizes-top-latina-influencer-laura-termini\/","title":{"rendered":"#LATISM13 reconoce a Laura Termini como Top Latina Influyente"},"content":{"rendered":"<p>MIAMI, Florida \u2013 17 de septiembre de 2013 \u2013 (HISPANICIZE WIRE) &#8211; Por segundo a\u00f1o consecutivo, LATISM, la organizaci\u00f3n m\u00e1s grande de latinos en los medios sociales en los Estados Unidos ha seleccionado a Laura Termini como mujer influyente Latina durante la Conferencia #Latism13 en la ciudad de Nueva York.<\/p>\n<p>El a\u00f1o pasado, 50 de las mejores voces latinas del pa\u00eds visitaron a La Casa Blanca para discutir temas claves que afectan a sus comunidades. Este a\u00f1o el visitar\u00e1s las Naciones Unidas, para reunirse con altos funcionarios de la Secretar\u00eda.<\/p>\n<blockquote><p>\u00abTermini estar\u00e1 en la sede de las Naciones Unidas en Nueva York para reunirse con altos funcionarios de la Secretar\u00eda\u00bb<\/p><\/blockquote>\n<p>Laura Termini, fundadora de la multi plataforma <a href=\"http:\/\/ChicaNOL.com\" target=\"_blank\" rel=\"noopener\">ChicaNOL.com<\/a> tiene el honor de formar parte del distinguido grupo de mujeres de negocios en l\u00ednea que llevar\u00e1n su mensaje y  voz \u00fanica como blogueras y personas influyentes en los medios de comunicaci\u00f3n social con un liderazgo ejemplar.<\/p>\n<p>El 18 de septiembre, Termini estar\u00e1 en la sede de las Naciones Unidas en Nueva York para reunirse con altos funcionarios de la Secretar\u00eda. Hablar\u00e1 de c\u00f3mo su plataforma <a href=\"http:\/\/www.ChicaNOL.com\" target=\"_blank\" rel=\"noopener\">www.ChicaNOL.com<\/a>, es un ejemplo dentro del mundo de negocios y de mujeres influyentes en TV, radio, editorial y medios sociales.<\/p>\n<p><strong>RECONOCIMIENTOS:<\/strong><br \/>\n&#8212; Fundador\/Editor ChicaNOL.com portal de bienestar.<br \/>\n&#8212; Certified by LATISM the largest organization of Latinos in Social Media as 2012\/2013 US Top Latina Blogger.<br \/>\n&#8212; 2013\/2012 Hispanicize Speaker<br \/>\n&#8212; 2013 Green Life Miami Spokesperson<br \/>\n&#8212; 2012\/2013 Latism Award Best Health blog<br \/>\n&#8212; 2012 Niche Mommy spotlight<br \/>\n&#8212; 2011 Woman of the week Noti Mujer CNNlatino<br \/>\n&#8212; 2011 AOL and The Huffington Post Spotlight<br \/>\n&#8212; 2011 St Jude Influencer Corner<br \/>\n&#8212; 2009 \u201c25 Myths 25 Realities \u201cAids Campaign Spokesperson<\/p>\n<p>Para saber m\u00e1s visita <a href=\"http:\/\/lauratermini.com\" target=\"_blank\" rel=\"noopener\">http:\/\/lauratermini.com<\/a>.<br \/>\nPuedes seguirla Twitter <a href=\"https:\/\/twitter.com\/@lauratermini\" target=\"_blank\" rel=\"noopener\">@lauratermini<\/a><br \/>\n<a href=\"https:\/\/Facebook.com\/naturalorganicaylatina\" target=\"_blank\" rel=\"noopener\">https:\/\/Facebook.com\/naturalorganicaylatina<\/a><br \/>\nVisita el blog: <a href=\"http:\/\/www.chicanol.com\" target=\"_blank\" rel=\"noopener\">http:\/\/www.chicanol.com<\/a> <\/p>\n<p>Disponible para entrevistas en New York del 18 de septiembre hasta el 26 de septiembre, llame al (786) 571-8271.<\/p>\n<p>Para Conferencias, Social Media Brand Ambassador y oportunidades de sponsorship, por favor escribir a marketing@chicanol.com.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MIAMI, Florida \u2013 17 de septiembre de 2013 \u2013 (HISPANICIZE WIRE) &#8211; Por segundo a\u00f1o consecutivo, LATISM, la organizaci\u00f3n m\u00e1s grande de latinos en los medios sociales en los Estados Unidos ha seleccionado a Laura Termini como mujer influyente Latina durante la Conferencia #Latism13 en la ciudad de Nueva York. El a\u00f1o pasado, 50 de&#8230; <a href=\"https:\/\/www.noticiasnewswire.com\/es\/latism13-recognizes-top-latina-influencer-laura-termini\/\" class=\"learn-btn\">Continue Reading<\/a><\/p>\n","protected":false},"author":2,"featured_media":2177,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[2352,8],"tags":[],"class_list":{"0":"post-18215","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-moda-belleza","8":"category-fashion-beauty","9":"entry"},"acf":[],"featured_image_src":"https:\/\/www.noticiasnewswire.com\/wp-content\/uploads\/2013\/09\/Untitled.jpg","featured_image_src_square":"https:\/\/www.noticiasnewswire.com\/wp-content\/uploads\/2013\/09\/Untitled.jpg","author_info":{"display_name":"mruiz","author_link":"https:\/\/www.noticiasnewswire.com\/es\/author\/mruiz\/"},"_links":{"self":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts\/18215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/comments?post=18215"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts\/18215\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/media\/2177"}],"wp:attachment":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/media?parent=18215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/categories?post=18215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/tags?post=18215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}