{"id":18837,"date":"2016-08-02T15:02:02","date_gmt":"2016-08-02T19:02:02","guid":{"rendered":"http:\/\/staging.hispanicizewire.com\/es\/?p=12409"},"modified":"2017-02-15T11:04:15","modified_gmt":"2017-02-15T16:04:15","slug":"jcpenney-atrae-a-los-compradores-del-regreso-a-la-escuela-con-estilos-y-ofertas-que-valen-hasta-el-ultimo-centavo","status":"publish","type":"post","link":"https:\/\/www.noticiasnewswire.com\/es\/jcpenney-atrae-a-los-compradores-del-regreso-a-la-escuela-con-estilos-y-ofertas-que-valen-hasta-el-ultimo-centavo\/","title":{"rendered":"JCPenney atrae a los compradores del regreso a la escuela con estilos y ofertas que valen hasta el \u00faltimo centavo"},"content":{"rendered":"<p>PLANO, TX &#8211; 2 de agosto de 2016 \u2013 (HISPANICIZE WIRE) &#8211; Para esta temporada del regreso a la escuela, JCPenney seleccion\u00f3 el mejor surtido de ropa, zapatos y accesorios de moda para que todos los ni\u00f1os puedan empezar el nuevo a\u00f1o escolar con un look que sea #HazValerTusPenneys. \u201cSo You. So Worth It\u201d es el eslogan inspirador que define a la nueva campa\u00f1a de marketing multimedia del regreso a la escuela, que debuta el 24 de julio. Adem\u00e1s, para ayudar a que las compras del regreso a la escuela sean a\u00fan m\u00e1s f\u00e1ciles, la compa\u00f1\u00eda lanz\u00f3 una aplicaci\u00f3n m\u00f3vil redise\u00f1ada de JCPenney, que ofrece una experiencia simplificada de compras, y expandi\u00f3 la opci\u00f3n de \u201cComprar en l\u00ednea y recoger en la tienda el mismo d\u00eda\u201d a todas las tiendas a nivel nacional. Hay m\u00e1s de 150,000 art\u00edculos en jcp.com que est\u00e1n disponibles para recoger el mismo d\u00eda en cualquier tienda de JCPenney, lo que les brinda a los clientes una ventaja con respecto a las listas de compras del regreso a la escuela.<\/p>\n<p>\u201cEl regreso a la escuela representa un inicio nuevo y una oportunidad para que las madres preparen a sus hijos para el pr\u00f3ximo a\u00f1o escolar. Ellas quieren que sus hijos se sientan seguros y la clave para lograr eso es dejarlos que sean ellos mismos. En JCPenney, tenemos los estilos y tendencias que le permiten a los ni\u00f1os expresar de mejor forma su personalidad, y todo a precios econ\u00f3micos,\u201d dijo Mary Beth West, directora de marketing y clientes de JCPenney. \u201cNuestra campa\u00f1a de marketing y promociones se enfocar\u00e1 de forma exclusiva en las madres modernas estadounidenses, que planificar\u00e1n varios viajes de compras para aprovechar los grandes ahorros, los estilos esenciales y las experiencias digitales convenientes que hacen que valga el tiempo comprar en JCPenney para toda la temporada del regreso a la escuela.\u201d<\/p>\n<p><strong>Ofertas para aprovechar que valen el tiempo <\/strong><\/p>\n<p>JCPenney contin\u00faa enfatizando el valor al cliente por ofrecer un rango de promociones durante el periodo popular de compras del regreso a la escuela. El minorista comienza la temporada con \u201cD\u00edas del Power Penney\u201d esta semana, al ofrecer una variedad de ofertas de $3, $5, $7 y $9 en art\u00edculos selectos, junto con varias ofertas de centavos de \u201ccompre uno y obtenga otro\u201d de marcas que solo se encuentran en JCPenney. <\/p>\n<p>El 22 y 23 de julio, se les dar\u00e1 la bienvenida a los compradores de JCPenney con un sobre que contiene un cup\u00f3n de $10 de descuento en una compra de $10, $20 de descuento en una compra de $20 o $100 de descuento en una compra de $100 o m\u00e1s, hasta agotar existencias. Adem\u00e1s, el 23 de julio y 7 de agosto, los asociados de tienda de JCPenney sorprender\u00e1n y deleitar\u00e1n a los clientes al regalar una cantidad limitada de cuadernos coloridos de \u201cpenny\u201d. El cuaderno incluye una <a href=\"http:\/\/www.jcpenney.com\/dotcom\/images\/BTS_checklist_7-7-16.pdf\" target=\"_blank\" rel=\"noopener\">lista de verificaci\u00f3n del regreso a la escuela<\/a> que destaca toda la ropa y equipo que necesitan los ni\u00f1os, junto con un cup\u00f3n que las madres pueden usar hasta seis veces durante la temporada. <\/p>\n<p>Los ni\u00f1os menores de 12 a\u00f1os pueden aprovechar los cortes de cabello de $10, desde ahora hasta el final de agosto en todos los salones de jcp y en el sal\u00f3n de InStyle. Para completar el look del regreso a la escuela, los lentes para ni\u00f1os menores de 16 a\u00f1os est\u00e1n disponibles por $39.99 en todos los centros \u00f3pticos de JCPenney.<\/p>\n<p><strong>Tendencias que valen el tiempo comprar<\/strong><\/p>\n<p>Las tendencias populares para las adolescentes que regresan a la escuela incluyen los encajes victorianos, faldas de pana, su\u00e9teres de equipos universitarios y babydolls, y para los adolescentes habr\u00e1 cuadros, capuchas, pantalones deportivos y chamarras de moto que dominar\u00e1n el estilo del nuevo a\u00f1o escolar. La <a href=\"http:\/\/www.jcpenney.com\/jsp\/browse\/cat.jump?id=cat1002910036\" target=\"_blank\" rel=\"noopener\">tienda del regreso a la escuela<\/a> de jcp.com destaca los mejores looks y m\u00e1s cosas en un formato para comprar con facilidad. Para proporcionar a\u00fan m\u00e1s inspiraci\u00f3n para las compras, JCPenney cre\u00f3 \u201cOutfits You\u2019ll Love\u201d en jcp.com, que destaca ocho piezas elegantes que se pueden combinar con lo equivalente a dos semanas de atuendos para cada grupo de edad escolar.<\/p>\n<p>Cuando se trata de tendencias del regreso a la escuela, JCPenney es el mejor destino de compras, gracias a los estilos y las marcas que los estudiantes quieren y a la calidad y el valor que las madres consideran #HazValerTusPenneys. A continuaci\u00f3n se presentan algunos cuantos ejemplos: <\/p>\n<p>&#8212; <strong>Art\u00edculos esenciales de mezclilla<\/strong>: Un nuevo a\u00f1o escolar es sin\u00f3nimo de un nuevo par de jeans y JCPenney tiene las tendencias de mezclilla m\u00e1s recientes, que incluyen los acampanados, ajustados, destruidos, de cintura alta, de parches y jegging para comenzar el a\u00f1o escolar con estilo. Con las mejores marcas como Levi\u2019s\u00ae, The Original Arizona Jean Company\u00ae y Total Girl\u00ae, los ni\u00f1os y adolescentes encontrar\u00e1n las marcas, tallas y moda que se ajustan a sus personalidades.<\/p>\n<p>&#8212; S<strong>iempre activo:<\/strong> Para los ni\u00f1os que andan de un lado a otro, JCPenney tiene un gran surtido de ropa deportiva de marcas clave que incluyen Xersion\u2122, City Streets\u00ae y Nike\u00ae. Xersion y Nike ahora est\u00e1n disponibles para los ni\u00f1os de edad preescolar en algunas tiendas de JCPenney y en jcp.com, lo que les permite a los estudiantes m\u00e1s j\u00f3venes vestirse igual que los ni\u00f1os grandes. <\/p>\n<p>&#8212; <strong>Nuevos zapatos:<\/strong> JCPenney tiene los zapatos para ayudarle a cualquier ni\u00f1o a comenzar de la mejor forma, con marcas populares como Nike, Converse\u00ae y Vans\u00ae. Los <a href=\"http:\/\/www.jcpenney.com\/shoes\/shop-brands\/view-all-brands\/xersion\/_\/N-1nvzvjZo4\/cat.jump?id=cat100590175&#038;deptId=dept20000018&#038;marketingSlot=true\" target=\"_blank\" rel=\"noopener\">zapatos deportivos de Xersion<\/a> son un producto nuevo este a\u00f1o, est\u00e1n disponibles para ni\u00f1os y ni\u00f1as y son perfectos para jugar kickball durante el receso o para pasar el tiempo con los amigos. <\/p>\n<p>&#8212; T<strong>allas especiales:<\/strong> Para complementar la amplia selecci\u00f3n de tallas grandes para ni\u00f1os disponibles en tiendas y en jcp.com, JCPenney est\u00e1 ampliando la oferta de tallas grandes para adolescentes para el nuevo a\u00f1o escolar. Las adolescentes que buscan las tendencias m\u00e1s recientes que se ajusten a figuras m\u00e1s curvil\u00edneas ahora encontrar\u00e1n m\u00e1s opciones de moda y ropa deportiva e informal en prendas de tallas grandes para j\u00f3venes de Decree\u00ae, Arizona y City Streets. <\/p>\n<p>&#8212; <strong>Uniformes escolares:<\/strong> JCPenney contin\u00faa siendo la sede central de todo el a\u00f1o para los <a href=\"http:\/\/www.jcpenney.com\/shops\/school-uniforms\/cat.jump?id=cat1002790024&#038;subcatId=&#038;deptId=cat1002910036&#038;null\" target=\"_blank\" rel=\"noopener\">uniformes escolares<\/a>, ya que ofrece polos, pantalones, shorts, faldas, su\u00e9teres y m\u00e1s de IZOD\u00ae y Arizona en las tiendas. En las tiendas pueden encontrar una gran selecci\u00f3n de uniformes de talla especial, con una selecci\u00f3n ampliada en jcp.com de IZOD\u00ae, Arizona y French Toast\u00ae. <\/p>\n<p>&#8212; <strong>Compras para los universitarios:<\/strong> Para los estudiantes que van a la universidad, <a href=\"http:\/\/www.jcpenney.com\/for-the-home\/college-life\/cat.jump?id=cat1001360006&#038;deptId=dept20000011\" target=\"_blank\" rel=\"noopener\">la tienda de art\u00edculos de dormitorio<\/a> de JCPenney tiene todo lo necesario para hacer que el cuarto del dormitorio se sienta como el hogar, como por ejemplo ropa de cama extra grande de Expressions\u2122 y IZOD\u00ae, electrodom\u00e9sticos peque\u00f1os de Cooks by JCPenney Home\u2122 y Keurig\u00ae y decoraciones coloridas.<\/p>\n<p>&#8212; Inspiraci\u00f3n de la imaginaci\u00f3n: Permita que la tienda de <a href=\"http:\/\/www.jcpenney.com\/kids\/disney\/cat.jump?id=cat1003110020&#038;deptId=dept20000016&#038;cmJCP_T=G1&#038;cmJCP_C=D9\" target=\"_blank\" rel=\"noopener\">Disney\u00ae dentro de JCPenney<\/a> ayude a los peque\u00f1os a tener un inicio m\u00e1gico para el nuevo a\u00f1o escolar. Las loncheras, mochilas y estuches de l\u00e1pices destacan a algunos de los personajes m\u00e1s populares de Disney de Finding Dory, Frozen, Sofia the First, Cars y Toy Story, entre otros.<\/p>\n<p><strong>Estrellas que valen la pena conocer<\/strong><\/p>\n<p>JCPenney se conecta con millones de adolescentes conocedores de la tecnolog\u00eda como el patrocinador minorista exclusivo del tour nacional anual de Fullscreen Live de <a href=\"http:\/\/fullscreenlive.com\/#girls-night-in-2016\" target=\"_blank\" rel=\"noopener\">\u201cGirls Night In\u201d<\/a>. <a href=\"https:\/\/www.youtube.com\/user\/macbby11\" target=\"_blank\" rel=\"noopener\">Alisha Marie<\/a>, <a href=\"https:\/\/www.youtube.com\/user\/nikiandgabibeauty\" target=\"_blank\" rel=\"noopener\">Niki &#038; Gabi DeMartino<\/a>, <a href=\"https:\/\/www.youtube.com\/user\/TheRealAlysonStoner\/featured\" target=\"_blank\" rel=\"noopener\">Alyson Stoner<\/a> y <a href=\"https:\/\/www.youtube.com\/user\/glamwithjessie\" target=\"_blank\" rel=\"noopener\">Jessie Paege<\/a> son vloggers populares que destacan algo de lo mejor de la moda de YouTube, y tienen una base de seguidores combinada de m\u00e1s de 20 millones. Durante el tour nacional de 24 ciudades, las ni\u00f1as llevar\u00e1n a cabo un show variado interactivo con juegos, sketches, concursos, espect\u00e1culos musicales y bailes, y hasta sesiones personalizadas de estilismo de JCPenney con los miembros afortunados de cada audiencia. Las tiendas de JCPenney en Phoenix, Denver y Seattle organizar\u00e1n tres eventos en donde una estrella de Girls Night In participar\u00e1 en una sesi\u00f3n de preguntas y respuestas, discutir\u00e1 las tendencias de moda y exhibir\u00e1 sus looks favoritos del regreso a la escuela, que se encuentran solo en JCPenney. Durante la \u00faltima parada, las estrellas de redes sociales de Girls Night In se encargar\u00e1n de la cuenta de Snapchat de JCPenney y le dar\u00e1n a los seguidores un acceso exclusivo a lo que sucede detr\u00e1s del escenario.<\/p>\n<p><strong>Causas que vale la pena apoyar<\/strong><\/p>\n<p>JCPenney est\u00e1 expandiendo su asociaci\u00f3n de 20 a\u00f1os con el YMCA de los Estados Unidos (Y-USA) en esta temporada del regreso a la escuela al donar desde $1, hasta $250,000 por cada par de jeans Arizona que se venda desde ahora y hasta el 2 de septiembre. Esta donaci\u00f3n apoyar\u00e1 los programas de logros acad\u00e9micos de la Y, que ayudan a los ni\u00f1os en todo el pa\u00eds a llegar a su m\u00e1ximo potencial. JCPenney tambi\u00e9n organizar\u00e1 un evento comunitario del regreso a la escuela en una filial local de la Y en Los \u00c1ngeles, en donde ofrecer\u00e1 una barra de mezclilla de Arizona, cortes de cabello gratuitos, ex\u00e1menes de la vista, entretenimiento, juegos y m\u00e1s. Por otra parte, JCPenney Cares, una organizaci\u00f3n de caridad p\u00fablica 501(c)3, apoyar\u00e1 a la Y con una donaci\u00f3n adicional de $250,000.<\/p>\n<p>Para ver la selecci\u00f3n de im\u00e1genes y la versi\u00f3n en espa\u00f1ol de esta publicaci\u00f3n, visite <a href=\"http:\/\/jcpnewsroom.com\" target=\"_blank\" rel=\"noopener\">jcpnewsroom.com<\/a>. <\/p>\n<p>Para ver las im\u00e1genes de tendencias del regreso a la escuela, visite el libro de looks del regreso a la escuela del 2016 en el siguiente sitio web: <a href=\"http:\/\/www.jcpnewsroom.com\/lookbooks-bts2016.html\" target=\"_blank\" rel=\"noopener\">http:\/\/www.jcpnewsroom.com\/lookbooks-bts2016.html<\/a>.<\/p>\n<p><strong>Relaciones con los medios de JCPenney: <\/strong>(972) 431-3400 o jcpnews@jcp.com; S\u00edganos en @jcpnews.<\/p>\n<p><strong>Acerca de JCPenney:<\/strong><br \/>\nJ. C. Penney Company, Inc. (NYSE:JCP), uno de los m\u00e1s grandes minoristas de ropa y enseres del hogar del pa\u00eds, se encuentra en una misi\u00f3n para garantizar que todas las experiencias de compra hagan que el tiempo, dinero y esfuerzo de sus clientes valgan la pena. Ya sea al comprar en jcp.com o al visitar una de las m\u00e1s de 1000 tiendas a lo largo de los Estados Unidos y Puerto Rico, los clientes encontrar\u00e1n una amplia variedad de productos de una cartera destacada de marcas propias, exclusivas y nacionales. En apoyo a esta propuesta de valor tenemos el esp\u00edritu guerrero de m\u00e1s de 100 000 asociados de JCPenney alrededor del mundo, que se concentran en las tres prioridades estrat\u00e9gicas de la empresa: fortalecer las marcas propias, convertirnos en un minorista omnicanal de primera categor\u00eda e incrementar los ingresos por cliente. Si desea mayor informaci\u00f3n, visite <a href=\"http:\/\/jcp.com\" target=\"_blank\" rel=\"noopener\">jcp.com<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><em>&#8212; La compa\u00f1\u00eda anuncia recolecci\u00f3n del mismo d\u00eda de todos los pedidos de jcp.com en todas las tiendas &#8212;<\/em><\/p>\n","protected":false},"author":2,"featured_media":17463,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[2351,7,8,2352],"tags":[1749,311,1750],"class_list":{"0":"post-18837","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-familia-hogar","8":"category-family-living","9":"category-fashion-beauty","10":"category-moda-belleza","11":"tag-back-to-school","12":"tag-jcpenney","13":"tag-regreso-a-la-escuela","14":"entry"},"acf":[],"featured_image_src":"https:\/\/www.noticiasnewswire.com\/wp-content\/uploads\/2016\/08\/JCP-Featured.jpg","featured_image_src_square":"https:\/\/www.noticiasnewswire.com\/wp-content\/uploads\/2016\/08\/JCP-Featured.jpg","author_info":{"display_name":"mruiz","author_link":"https:\/\/www.noticiasnewswire.com\/es\/author\/mruiz\/"},"_links":{"self":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts\/18837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/comments?post=18837"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts\/18837\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/media\/17463"}],"wp:attachment":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/media?parent=18837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/categories?post=18837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/tags?post=18837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}