{"id":38772,"date":"2022-01-04T12:00:30","date_gmt":"2022-01-04T17:00:30","guid":{"rendered":"https:\/\/noticiaswire.wpengine.com\/?p=38772"},"modified":"2022-02-04T11:01:49","modified_gmt":"2022-02-04T16:01:49","slug":"jacqie-rivera-ceo-de-jenni-rivera-enterprises","status":"publish","type":"post","link":"https:\/\/www.noticiasnewswire.com\/es\/jacqie-rivera-ceo-de-jenni-rivera-enterprises\/","title":{"rendered":"Jacqie Rivera asume el cargo de CEO de Jenni Rivera Enterprises, LLC y JENNI RIVERA FASHION, LLC"},"content":{"rendered":"<img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.noticiasnewswire.com\/wp-content\/uploads\/2021\/12\/logo.jpg\" width=\"304\" height=\"186\"\/> <p><span style=\"font-weight: 400\">Huntington Park, CA \u2014 4 de Enero, 2022 \u2014 (<a href=\"\/es\/\">NOTICIAS NEWSWIRE<\/a>) \u2014 \u201cEn nombre de mis cuatro hermanos, estoy emocionada de asumir el puesto de directora ejecutiva de estas dos empresas para preservar el legado y la reputaci\u00f3n (al igual hacer crecer) de estos dos negocios que mi madre dej\u00f3 en manos de mi t\u00eda Rosie y ahora a mi. Esto representa el cambio de guardia de una generaci\u00f3n a otra, estoy complacida y agradecida de haber recibido la antorcha de liderazgo. Espero que nos embarquemos en nuevas y emocionantes oportunidades comerciales y estoy ansiosa por comenzar \u00ab, dijo la nueva directora ejecutiva Jacqie <\/span><span style=\"font-weight: 400\">Rivera<\/span><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Rivera a\u00f1adi\u00f3,<\/span><span style=\"font-weight: 400\"> \u201cEstoy agradecida por los esfuerzos que mi t\u00eda hizo en nuestro nombre despu\u00e9s del fallecimiento de nuestra madre para honrar sus deseos y atender nuestras necesidades financieras y emocionales durante los \u00faltimos 9 a\u00f1os. Ella sirvi\u00f3 en sus roles duales con orgullo e integridad. En preparaci\u00f3n para este cambio, se realiz\u00f3 una auditor\u00eda del Fideicomiso. A pesar de los informes recientes de los medios de comunicaci\u00f3n, no hubo evidencia de ning\u00fan delito, apropiaci\u00f3n indebida o robo de fondos fiduciarios por parte de Rosie, actuando como fideicomisaria. Los beneficiarios y yo le deseamos a nuestra t\u00eda Rosie la mejor de las suertes en todos sus nuevos esfuerzos y esperamos que nuestros esfuerzos en el futuro hagan que tanto ella como nuestra madre se sientan orgullosas de nosotros\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Rosie Rivera desea expresar el mayor apoyo a Jacqie al comienzo de este nuevo cap\u00edtulo. Al comentar sobre esta transici\u00f3n, Rosie deseaba ofrecer buenos deseos a su familia: \u201cDoy gracias a Dios y a mi hermana por confiarme su legado. Ha sido un privilegio y un honor. Mi hermana vale el peso de estos \u00faltimos 9 a\u00f1os y m\u00e1s, pero estoy feliz de pasar la batuta. Continuar\u00e9 orando por Jacqie mientras asume este papel y animando a mi hermana y mis sobrinos.\u00bb\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Huntington Park, CA \u2014 4 de Enero, 2022 \u2014 (NOTICIAS NEWSWIRE) \u2014 \u201cEn nombre de mis cuatro hermanos, estoy emocionada de asumir el puesto de directora ejecutiva de estas dos empresas para preservar el legado y la reputaci\u00f3n (al igual hacer crecer) de estos dos negocios que mi madre dej\u00f3 en manos de mi t\u00eda&#8230; <a href=\"https:\/\/www.noticiasnewswire.com\/es\/jacqie-rivera-ceo-de-jenni-rivera-enterprises\/\" class=\"learn-btn\">Continue Reading<\/a><\/p>\n","protected":false},"author":15,"featured_media":38771,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[2350,2352],"tags":[],"class_list":{"0":"post-38772","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-entretenimiento","8":"category-moda-belleza","9":"entry"},"acf":[],"featured_image_src":"https:\/\/www.noticiasnewswire.com\/wp-content\/uploads\/2021\/12\/featured-image-4-600x400.jpg","featured_image_src_square":"https:\/\/www.noticiasnewswire.com\/wp-content\/uploads\/2021\/12\/featured-image-4-600x463.jpg","author_info":{"display_name":"vicente","author_link":"https:\/\/www.noticiasnewswire.com\/es\/author\/vicente\/"},"_links":{"self":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts\/38772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/comments?post=38772"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts\/38772\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/media\/38771"}],"wp:attachment":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/media?parent=38772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/categories?post=38772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/tags?post=38772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}