{"id":46363,"date":"2023-02-21T16:51:46","date_gmt":"2023-02-21T21:51:46","guid":{"rendered":"https:\/\/www.noticiasnewswire.com\/?p=46363"},"modified":"2023-02-23T11:10:28","modified_gmt":"2023-02-23T16:10:28","slug":"festival-de-cine-de-miami","status":"publish","type":"post","link":"https:\/\/www.noticiasnewswire.com\/es\/festival-de-cine-de-miami\/","title":{"rendered":"Festival de Cine de Miami acoge cinta de Diario Las Am\u00e9ricas"},"content":{"rendered":"<iframe loading=\"lazy\" class=\"youtube\" width=\"304\" height=\"186\" src=\"https:\/\/youtube.com\/embed\/L4-XzdY8BjE?wmode=transparent\" frameborder=\"0\" wmode=\"transparent\"><\/iframe> <p>MIAMI, FL \u2014 21 de febrero de 2023 \u2014 (<a href=\"https:\/\/www.noticiasnewswire.com\/es\/\">NOTICIAS NEWSWIRE<\/a>) \u2014 El documental <strong>\u00abEl adi\u00f3s de la esperanza\u00bb<\/strong>, una producci\u00f3n del peri\u00f3dico\u00a0<strong>DIARIO LAS AM\u00c9RICAS<\/strong>, fue seleccionado por el\u00a0<strong>Festival de Cine de Miami<\/strong>\u00a0en su 40.a edici\u00f3n, que tendr\u00e1 lugar del 3 al 12 de marzo. El material audiovisual est\u00e1\u00a0<a href=\"https:\/\/miamifilmfestival2023.eventive.org\/films\/63d8210109050900cfb004d7\" target=\"_blank\" rel=\"follow noopener\">programado<\/a>\u00a0para proyectarse el lunes 6 de marzo a las 7:15 pm en el Silverspot Cinema 16 (300 SE 3rd St #100, Miami, FL 33131).<\/p>\n<p>\u00abEl adi\u00f3s de la esperanza\u00bb (\u201cJourney to Hope\u201d en su versi\u00f3n en ingl\u00e9s) recrea las experiencias vividas por cinco de los ni\u00f1os que integran el grupo de 14.000 menores que hace 60 a\u00f1os fueron enviados a EEUU sin sus padres en un \u00e9xodo masivo que se llev\u00f3 a cabo de manera clandestina. En el material se presentan detalles \u00edntimos de la desgarradora separaci\u00f3n familiar causada por este \u00e9xodo, en los testimonios de Antonio \u00abTony\u00bb Argiz, Eduardo \u00abEddy\u00bb Alvarez, Aida Levitan, Eduardo Padr\u00f3n, y Enrique \u00abRic\u00bb Prado.<\/p>\n<p>La\u00a0<a href=\"https:\/\/miamifilmfestival2023.eventive.org\/films\/63d8210109050900cfb004d7\" target=\"_blank\" rel=\"follow noopener\">cinta<\/a>\u00a0est\u00e1 dirigida por Lieter Ledesma, un actor, presentador y director cubano que ha actuado en m\u00e1s de diez pel\u00edculas en Cuba, Espa\u00f1a y Brasil. Este documental es su \u00f3pera prima. El equipo lo integran Iliana Lavastida (directora ejecutiva de DIARIO LAS AM\u00c9RICAS), Wilma Hern\u00e1ndez y Grethel Delgado en calidad de guionistas. En la producci\u00f3n colaboraron: Iliana Lavastida, Aida Levitan, Darcy Borrero, Silvio Campos, Grethel Delgado, Jes\u00fas Hern\u00e1ndez, Wilma Hern\u00e1ndez, Rafael Marrero, y Camila Mendoza. Loam Jo se encarg\u00f3 de la cinematograf\u00eda; la edici\u00f3n estuvo a cargo de Iv\u00e1n Pedraza y la m\u00fasica es de Leo Teruel.<\/p>\n<p><strong>Una\u00a0<a href=\"https:\/\/www.diariolasamericas.com\/pedropan\" target=\"_blank\" rel=\"follow noopener\">revista<\/a>, un documental, una memoria compartida<\/strong><\/p>\n<p>Este documental forma parte de un trabajo de largo aliento que DIARIO LAS AM\u00c9RICAS realiza sobre la operaci\u00f3n Pedro Pan, con vistas a rescatar valiosos testimonios de quienes protagonizaron dicho \u00e9xodo. Entre las labores period\u00edsticas se organizaron art\u00edculos period\u00edsticos, una revista y el presente audiovisual. Puede acceder a los materiales de la revista, tanto la\u00a0<a href=\"https:\/\/www.diariolasamericas.com\/ediciones-especiales\/revista-especial-operacion-pedro-pan-n4237272\" target=\"_blank\" rel=\"follow noopener\">edici\u00f3n digitalizada<\/a>\u00a0como las entrevistas independientes con sus videos,\u00a0<a href=\"https:\/\/www.diariolasamericas.com\/pedropan\" target=\"_blank\" rel=\"follow noopener\">en este enlace<\/a>.<\/p>\n<p>A los cinco entrevistados para el documental se suman: Willy Chirino y Lissette \u00c1lvarez, el arzobispo de Miami Thomas Wenski, Tom\u00e1s Regalado, Elo\u00edsa M. Echazabal, Joe Carollo, Armando Codina, Max Alvarez, Rosa Sueiro, Armando Vizca\u00edno, Jos\u00e9 Antonio Garc\u00eda, Vivian S\u00e1nchez, Roger L\u00f3pez, Benito Pratts, C\u00e9sar Pizarro, Celia Su\u00e1rez, y el Padre Fernando Her\u00eda.<\/p>\n<p>En junio de 2022 este rotativo realiz\u00f3 un evento para presentar la revista hom\u00f3nima que recoge historias relacionadas con el documental. La jornada tuvo lugar en el Koubek Center del Miami Dade College y cont\u00f3 con un c\u00f3ctel de bienvenida. Durante el evento se comparti\u00f3 la revista conmemorativa por el aniversario 60 de la operaci\u00f3n Pedro Pan, el mayor \u00e9xodo masivo de ni\u00f1os no acompa\u00f1ados que recoge la historia del hemisferio.<\/p>\n<p>Participaron en el evento varias personalidades locales, adem\u00e1s de los periodistas y el equipo del peri\u00f3dico.<\/p>\n","protected":false},"excerpt":{"rendered":"<h3><em>\u2014 El Festival de Cine de Miami seleccion\u00f3 el documental \u00abEl adi\u00f3s de la esperanza\u00bb, que recoge testimonios de los protagonistas de la operaci\u00f3n Pedro Pan \u2014<\/em><\/h3>\n","protected":false},"author":15,"featured_media":46350,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[2346,2354],"tags":[20607,18132],"class_list":["post-46363","post","type-post","status-publish","format-standard","has-post-thumbnail","category-arte-cultura","category-noticias-generales","tag-cine-es","tag-festival-es","entry"],"acf":[],"featured_image_src":"https:\/\/www.noticiasnewswire.com\/wp-content\/uploads\/2023\/02\/featured-image-16-600x400.jpg","featured_image_src_square":"https:\/\/www.noticiasnewswire.com\/wp-content\/uploads\/2023\/02\/featured-image-16-600x463.jpg","author_info":{"display_name":"vicente","author_link":"https:\/\/www.noticiasnewswire.com\/es\/author\/vicente\/"},"_links":{"self":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts\/46363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/comments?post=46363"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts\/46363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/media\/46350"}],"wp:attachment":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/media?parent=46363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/categories?post=46363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/tags?post=46363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}