{"id":51879,"date":"2024-03-18T11:41:16","date_gmt":"2024-03-18T15:41:16","guid":{"rendered":"https:\/\/www.noticiasnewswire.com\/?p=51879"},"modified":"2024-03-18T11:41:16","modified_gmt":"2024-03-18T15:41:16","slug":"healthmap-anuncia-inauguracion","status":"publish","type":"post","link":"https:\/\/www.noticiasnewswire.com\/es\/healthmap-anuncia-inauguracion\/","title":{"rendered":"Healthmap Solutions anuncia gran inauguraci\u00f3n en Puerto Rico"},"content":{"rendered":"<p>GUAYNABO, PR \u2014 18 de marzo de 2024 \u2014 (<a href=\"https:\/\/www.noticiasnewswire.com\/es\/\">NOTICIAS NEWSWIRE<\/a>) \u2014 Healthmap Solutions, Inc. (Healthmap), una empresa l\u00edder en el manejo de la salud de la poblaci\u00f3n renal, ha anunciado la gran apertura de su nueva oficina en Guaynabo, Puerto Rico. La ceremonia oficial de corte de cinta ser\u00e1 el martes 26 de marzo a las 8:30 a.m., hora del Atl\u00e1ntico, en las instalaciones arrendadas de 6,887 pies cuadrados de la compa\u00f1\u00eda en City View Plaza en # 48 PR State Road 165, Guaynabo. El evento contar\u00e1 con las palabras de apertura del Director Ejecutivo de Healthmap, Eric Reimer, el Director de Crecimiento, Tom Gaffney, y Nelson P\u00e9rez Surillo, JD, Vicepresidente de Operaciones en Puerto Rico. Despu\u00e9s del corte de cinta habr\u00e1 una recepci\u00f3n con oportunidades para entrevistas con los medios de comunicaci\u00f3n.<\/p>\n<p>El anuncio fue hecho por el Sr. Reimer, quien dijo: \u201cLa expansi\u00f3n de la compa\u00f1\u00eda a Puerto Rico es el resultado de la asociaci\u00f3n formada en el 2023 con un nuevo cliente con sede en San Juan. A trav\u00e9s de esta asociaci\u00f3n, estamos presentando el programa de Manejo de la Salud de la Poblaci\u00f3n Renal de Healthmap, comprobado y acreditado por el NCQA, a las personas en Puerto Rico que viven con enfermedad renal cr\u00f3nica\u201d.<\/p>\n<p>La divisi\u00f3n de Puerto Rico de Healthmap est\u00e1 dirigida por Nelson P\u00e9rez Surillo, un experimentado profesional de servicios de salud.<\/p>\n<p>\u201cNelson administra nuestro equipo de m\u00e1s de 70 empleados de tiempo completo provenientes de toda la isla, incluyendo enfermeros expertos, dietistas, trabajadores sociales y otros profesionales, todos los cuales entienden la cultura y los matices del mercado\u201d, dijo el Sr. Reimer. El Director M\u00e9dico Lisandro Montalvo-Burke, MD, un nefr\u00f3logo certificado que ha ejercido en Can\u00f3vanas, PR desde el 2005, tambi\u00e9n apoyar\u00e1 las iniciativas cl\u00ednicas del equipo de Healthmap en la regi\u00f3n.<\/p>\n<p>El innovador programa de Manejo de la Salud de la Poblaci\u00f3n Renal de la compa\u00f1\u00eda con sede en Florida ha tenido \u00e9xito en mejorar el cuidado y reducir los costos para los pacientes con enfermedad renal cr\u00f3nica (CKD) y enfermedad renal en etapa terminal (ESRD). Seg\u00fan el Sr. Reimer, \u201cel equipo de Healthmap apoya el cuidado hol\u00edstico y centrado en el paciente para CKD y ESRD a trav\u00e9s de la colaboraci\u00f3n con los pacientes y un espectro completo de proveedores. Nos enfocamos en la participaci\u00f3n, la identificaci\u00f3n temprana, retrasar el progreso de la enfermedad y la terapia de reemplazo renal planificada, a la misma vez que reducimos las visitas a salas de emergencia innecesarias, las admisiones hospitalarias y readmisiones.<\/p>\n<p>\u201cSabemos que los proveedores de cuidado m\u00e9dico en Puerto Rico tienen una gran carga de trabajo\u201d, continu\u00f3 el Sr. Reimer. \u201cNuestro objetivo es aumentar su capacidad para brindar un cuidado excepcional y un mayor acceso a programas cl\u00ednicos sin interrumpir su flujo de trabajo\u201d.<\/p>\n<h3>Acerca de Healthmap Solutions<\/h3>\n<p>Healthmap Solutions es una empresa de manejo de la salud de la poblaci\u00f3n renal acreditada por el NCQA que presta servicios a planes m\u00e9dicos, sistemas de salud, organizaciones de cuidado responsable y grupos de proveedores que buscan una soluci\u00f3n para mejorar la vida de los americanos que viven con enfermedad renal cr\u00f3nica. Utilizando su avanzada tecnolog\u00eda de an\u00e1lisis predictivo y su experiencia cl\u00ednica, Healthmap proporciona una identificaci\u00f3n temprana de la enfermedad renal y recomienda intervenciones cl\u00ednicamente probadas para retrasar la progresi\u00f3n de la enfermedad. Los equipos de navegaci\u00f3n de cuidado de Healthmap trabajan con los pacientes y todo el espectro de proveedores de un plan m\u00e9dico para mantener el acceso, minimizar las interrupciones y brindar cuidado personalizado e integral de parte de su proveedor de confianza. El enfoque de Healthmap es planificar de manera proactiva las transiciones de cuidado y optimizar la terapia de reemplazo renal, con un enfoque en el tratamiento de di\u00e1lisis en el hogar y trasplante. Este enfoque mejora el cuidado, los resultados y la experiencia del paciente, al mismo tiempo que reduce los costos m\u00e9dicos para los planes m\u00e9dicos y grupos de proveedores.<\/p>\n","protected":false},"excerpt":{"rendered":"<h3><em>\u2014 La expansi\u00f3n trae programa de manejo de salud renal y empleos a Puerto Rico \u2014<\/em><\/h3>\n","protected":false},"author":15,"featured_media":51878,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[2354,2355],"tags":[],"class_list":{"0":"post-51879","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-generales","8":"category-salud","9":"entry"},"acf":[],"featured_image_src":"https:\/\/www.noticiasnewswire.com\/wp-content\/uploads\/2024\/03\/featured-image-03181-600x400.jpg","featured_image_src_square":"https:\/\/www.noticiasnewswire.com\/wp-content\/uploads\/2024\/03\/featured-image-03181-600x463.jpg","author_info":{"display_name":"vicente","author_link":"https:\/\/www.noticiasnewswire.com\/es\/author\/vicente\/"},"_links":{"self":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts\/51879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/comments?post=51879"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts\/51879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/media\/51878"}],"wp:attachment":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/media?parent=51879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/categories?post=51879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/tags?post=51879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}