{"id":52630,"date":"2024-05-17T09:00:05","date_gmt":"2024-05-17T13:00:05","guid":{"rendered":"https:\/\/www.noticiasnewswire.com\/?p=52630"},"modified":"2024-05-17T08:14:27","modified_gmt":"2024-05-17T12:14:27","slug":"fiap-face-to-face-webinar-21-de-mayo","status":"publish","type":"post","link":"https:\/\/www.noticiasnewswire.com\/es\/fiap-face-to-face-webinar-21-de-mayo\/","title":{"rendered":"FIAP Face to Face Webinar: Innovaci\u00f3n y Estrategia Sostenible: Transformando Negocios para el Futuro este martes 21 de mayo"},"content":{"rendered":"<p>MIAMI, FL \u2014 17 de mayo de 2024 \u2014 (<a href=\"https:\/\/www.noticiasnewswire.com\/es\/\">NOTICIAS NEWSWIRE<\/a>) \u2014 En la pr\u00f3xima edici\u00f3n del FIAP Face to Face Webinar se explorar\u00e1 c\u00f3mo las empresas pueden fusionar innovaci\u00f3n y sostenibilidad en sus estrategias corporativas para no solo adaptarse a los mercados en evoluci\u00f3n, sino tambi\u00e9n liderar a clientes hacia un futuro sustentable.<\/p>\n<p>El webinar \u201cInnovaci\u00f3n y Estrategia Sostenible: Transformando Negocios para el Futuro\u201d contar\u00e1 con la participaci\u00f3n de Stephanie Bakkum, directora de Consultor\u00eda Global de Sostenibilidad en Ogilvy Consulting, desde Nueva York, y C\u00e9sar Holgu\u00edn, Chief Strategy Officer y Managing Director en Ogilvy Consulting y Ogilvy Experience, desde M\u00e9xico. Ambos ofrecer\u00e1n m\u00e9todos sencillos para implementar pr\u00e1cticas sostenibles que adem\u00e1s de mejorar la competitividad, generan tambi\u00e9n un impacto significativo en la sociedad y el medio ambiente.<\/p>\n<p>Este webinar,crucial para cualquier l\u00edder empresarial o innovador que busque integrar la sostenibilidad como un pilar de crecimiento y transformaci\u00f3n en su organizaci\u00f3n, ser\u00e1 moderado por Mara Fern\u00e1ndez, Chief Transformation Officer de PRODU.<\/p>\n<p>El webinar se realizar\u00e1 el pr\u00f3ximo martes 21 de mayo a las 12pm (Miami).<\/p>\n<p>Para participar reg\u00edstrese <strong><a href=\"https:\/\/www.produ.com\/webinar\/innovacion-y-estrategia-sostenible-transformando-negocios-para-el-futuro\/\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a><\/strong><\/p>\n<h3>Acerca del FIAP<\/h3>\n<p>El Festival Iberoamericano de la Creatividad, FIAP, entra en su edici\u00f3n 55 para continuar reconociendo la creatividad en todos los formatos publicitarios de Iberoam\u00e9rica. En sociedad con PRODU, el proveedor l\u00edder de informaci\u00f3n de la industria del entretenimiento, la publicidad y la tecnolog\u00eda de habla hispana, presentan un nuevo concepto: reconocer la excelencia en ideas que transforman, inspiran, elevan y apasionan audiencias en la regi\u00f3n y m\u00e1s all\u00e1.<\/p>\n<p><b>Acerca de PRODU<\/b><br \/>\nEste 2024, PRODU cumple 35 a\u00f1os siendo el proveedor l\u00edder de contenido para los profesionales de la televisi\u00f3n, la publicidad y la tecnolog\u00eda en Latinoam\u00e9rica, Espa\u00f1a y el mercado hispano de EE\u202fUU. PRODU genera publicaciones comerciales peri\u00f3dicas, ahora todas digitales en consonancia con el cuidado del planeta, y un directorio en l\u00ednea: Who\u2019s Who Online, adem\u00e1s del sitio web y los boletines de noticias m\u00e1s prestigiosos y consultados sobre las industrias de televisi\u00f3n, publicidad y tecnolog\u00eda. Adicionalmente, PRODU ofrece tres boletines informativos gratuitos que llegan a m\u00e1s de 30.000 tomadores de decisiones y profesionales ejecutivos todos los d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MIAMI, FL \u2014 17 de mayo de 2024 \u2014 (NOTICIAS NEWSWIRE) \u2014 En la pr\u00f3xima edici\u00f3n del FIAP Face to Face Webinar se explorar\u00e1 c\u00f3mo las empresas pueden fusionar innovaci\u00f3n y sostenibilidad en sus estrategias corporativas para no solo adaptarse a los mercados en evoluci\u00f3n, sino tambi\u00e9n liderar a clientes hacia un futuro sustentable. El&#8230; <a href=\"https:\/\/www.noticiasnewswire.com\/es\/fiap-face-to-face-webinar-21-de-mayo\/\" class=\"learn-btn\">Continue Reading<\/a><\/p>\n","protected":false},"author":15,"featured_media":52629,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[2358,2359],"tags":[],"class_list":{"0":"post-52630","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internet-tecnologia","8":"category-marketing-es","9":"entry"},"acf":[],"featured_image_src":"https:\/\/www.noticiasnewswire.com\/wp-content\/uploads\/2024\/05\/Facetoface_695x463_2024_MAY-21-600x400.png","featured_image_src_square":"https:\/\/www.noticiasnewswire.com\/wp-content\/uploads\/2024\/05\/Facetoface_695x463_2024_MAY-21-600x463.png","author_info":{"display_name":"vicente","author_link":"https:\/\/www.noticiasnewswire.com\/es\/author\/vicente\/"},"_links":{"self":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts\/52630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/comments?post=52630"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/posts\/52630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/media\/52629"}],"wp:attachment":[{"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/media?parent=52630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/categories?post=52630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasnewswire.com\/es\/wp-json\/wp\/v2\/tags?post=52630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}